{"id":928,"date":"2009-12-15T18:11:24","date_gmt":"2009-12-15T18:11:24","guid":{"rendered":"https:\/\/satmediawp.edv-kroiss.com\/produkt\/interne-500-gb-hdd-25-sata-geraeuscharm\/"},"modified":"2026-07-10T13:35:43","modified_gmt":"2026-07-10T11:35:43","slug":"interne-500-gb-hdd-25-sata-geraeuscharm","status":"publish","type":"product","link":"http:\/\/satmedia.at\/en\/product\/interne-500-gb-hdd-25-sata-geraeuscharm\/","title":{"rendered":"Interne 500GB HDD 2,5 SATA Ger\u00e4uscharm"},"content":{"rendered":"<p>Diese Festplatte wird extra produziert f\u00fcr Digital Receiver und DVD-Brenner und verf\u00fcgt \u00fcber 5400U\/min. Die Platten zeichnet sich aus durch eine geringe Stromaufnahme und einem leisen Lauf!<\/p>","protected":false},"excerpt":{"rendered":"<p>Diese Festplatte wird extra produziert f\u00fcr Digital Receiver und DVD-Brenner und verf\u00fcgt \u00fcber 5400U\/min. Die Platten zeichnet sich aus durch eine geringe Stromaufnahme und einem leisen Lauf!<\/p>","protected":false},"featured_media":926,"template":"","meta":{"powered_cache_disable_cache":false,"powered_cache_disable_lazyload":false,"powered_cache_disable_css_optimization":false},"product_cat":[50,96],"product_tag":[],"_links":{"self":[{"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/product\/928"}],"collection":[{"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/media\/926"}],"wp:attachment":[{"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/product_cat?post=928"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/satmedia.at\/en\/wp-json\/wp\/v2\/product_tag?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}